{"id":61,"date":"2021-10-17T19:48:58","date_gmt":"2021-10-17T19:48:58","guid":{"rendered":"http:\/\/remax-rio.com.ar\/?page_id=61"},"modified":"2026-08-03T11:54:47","modified_gmt":"2026-08-03T11:54:47","slug":"agentes","status":"publish","type":"page","link":"https:\/\/remax-rio.com.ar\/index.php\/agentes\/","title":{"rendered":"Agentes"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbHero section\u00bb _builder_version=\u00bb4.16&#8243; use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(150,105,97,0.67) 0%|rgba(2,0,76,0.84) 100%\u00bb background_color_gradient_overlays_image=\u00bbon\u00bb background_color_gradient_start=\u00bbrgba(150,105,97,0.67)\u00bb background_color_gradient_end=\u00bbrgba(2,0,76,0.84)\u00bb background_image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/10\/real-estate-13-1.jpg\u00bb background_position=\u00bbtop_center\u00bb custom_margin=\u00bb|||\u00bb custom_padding=\u00bb10%||14%|\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb2_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_margin=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb2_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb1px|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.16&#8243; text_font=\u00bbLato||||||||\u00bb text_font_size=\u00bb20px\u00bb text_line_height=\u00bb1.8em\u00bb header_font=\u00bbLato|900|||||||\u00bb header_font_size=\u00bb80px\u00bb header_letter_spacing=\u00bb2px\u00bb header_line_height=\u00bb1.2em\u00bb background_layout=\u00bbdark\u00bb animation_style=\u00bbfold\u00bb header_font_size_tablet=\u00bb46px\u00bb header_font_size_phone=\u00bb\u00bb header_font_size_last_edited=\u00bbon|tablet\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h1>Nuestros Agentes<\/h1>\n<h3 data-css=\"tve-u-16eec487c68\" class=\"\"><span>Te presentamos los mejores agentes inmobiliarios que en equipo, junto con la martillera te ayudar\u00e1n a cumplir tus sue\u00f1os, porque en RE \/ MAX RIO lo m\u00e1s importante sos vos.<\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_code _builder_version=\u00bb4.16.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<a href=\"https:\/\/wa.me\/541131846889?text=\u00a1Hola!%20\u00bfC\u00f3mo%20est\u00e1s%3F\" target=\"_blank\" style='color:white' rel=\"noopener\"><span class='container-whatsapp'><i class=\"fa-brands fa-whatsapp\"><\/i><\/span><\/a>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbTeam\u00bb _builder_version=\u00bb4.16.1&#8243; custom_margin=\u00bb|||\u00bb custom_padding=\u00bb54px|0px|100px|0px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb width=\u00bb88.5%\u00bb custom_margin=\u00bb-10%|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb border_color_all=\u00bb#3c39e6&#8243; border_width_top=\u00bb18px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAna Ramirez Rufino\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/ana-ramirez-rufino\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/ANA-RAMIREZ.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb122px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb24.4px\u00bb custom_padding=\u00bb0px|||||\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb +54 91153352635&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_padding=\u00bb||4px|||\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbanaramirezr@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbNoemi Garcia Cueva\u00bb url=\u00bbhttp:\/\/remax.com.ar\/agent\/noemi-garcia-cueva\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/10\/noemi-300&#215;300.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91159286904&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbnoemigc@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFlorencia Da Silva\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/florencia-da-silva\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/FLORENCIA-DA-SILVA.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91141971695&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfdasilva@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGraciela Cesare\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/graciela-cesare\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/04\/GRACIELA-CESARE.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb89px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91151330629&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbgcesare@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbNancy Vergara\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/nancy-vergara\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/Diseno-sin-titulo-5.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-40px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91144353956&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbnancyv@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFlorencia Perucha\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/florencia-perucha\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/FLORENCIA-PERUCHA.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91163638005&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfperucha@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDiana Falicoff\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/diana-falicoff\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/Gemini_Generated_Image_r1hfskr1hfskr1hf-e1777342020438.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91165100591&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbdfalicoff@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAndrea Barrios\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/andrea-barrios\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/ANDREA-BARRIOS-scaled.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91138230819&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbabarrios@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMaria Cristina Coronel\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/maria-cristina-coronel\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/09\/CRISTINA-CORONEL-2-1-e1756933046503.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91131501041&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmccoronel@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|-6px||||\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px||\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSusana Izzo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/susana-izzo\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/SUSANA-IZZO-scaled.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91163352649&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbsusanai@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDora V\u00e9lez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/dora-velez\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/10\/12-300&#215;245.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb130px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91161194771&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbvelezd@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAntonela D&#8217;iorio\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/antonela-d-iorio\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2023\/12\/Perfil-Anto-2023-Fondo-Blanco-scaled.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91150512808&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbadiorio@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMar\u00eda Emilia Marello\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/maria-emilia-marello\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/10\/emilia-300&#215;300.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb +54 91134194020&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmmarello@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDiana Ribera\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/diana-ribera\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/10\/dian-300&#215;300.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 91144079787&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbdribera@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSebastian Barrios\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/sebastian-barrios\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2021\/11\/IMG_6144.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb +54 91126380576&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbsbarrios@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16.1&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDiego Evangelista\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/diego-evangelista\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/02\/DIEGO-EVANGELISTA-JPG-1.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb +54 91130189662&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbdevangelista@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbHernan Capalbo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/hernan-capalbo\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2022\/09\/Hernan-Capalbo-1.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1154261452&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbhcapalbo@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16.1&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbMarcela Arancibia\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/marcela-arancibia\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2022\/11\/Foto-Marcela-Arancibia.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1164833864&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmarancibia@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbElsa Aversa\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/elsa-aversa\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/ELSIE.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-30px||||false|false\u00bb min_height=\u00bb97.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1165671426&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb28px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbeaversa@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb28px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMercedes Serena Cottet\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/mercedes-serena-cottet\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2023\/02\/Mercedes-Serena-Cottet.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb min_height=\u00bb90.5px\u00bb custom_padding=\u00bb||0px|||\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 911 59912322&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmserenacottet@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbJuan Jose Casaglia\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/juan-jose-casaglia\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2023\/05\/WhatsApp-Image-2023-05-02-at-16.59.24-PhotoRoom.png-PhotoRoom.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb90.5px\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1150626084&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbjcasaglia@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bb Agustina Scarinci\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/agustina-scarinci\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/03\/AGUSTINA-SCARINCI-SIN-FONDO-1.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1156538088&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbascarinci@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGaston Petrola\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/gaston-petrola\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/GASTON-PETROLA.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb90px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1132080226&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbgpetrola@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMariano Prieto\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/mariano-prieto\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2023\/12\/agentImage34482940_27_11_2023_02_36_57.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb90px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1136184636&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmprietro@remax.com.ar \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbClaudia Martino\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/claudia-martino\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/CLAU.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb81px\u00bb content_max_width=\u00bb500px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1160124590&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmartinoc@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSilvina Sanabria\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/silvina-sanabria\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/02\/SILVINA-SANABRIA.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb90px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1167572945&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbssanabria@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbJuan Iozzolino\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/juan-iozzolino\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/02\/JUAN-IOZZOLINO.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb90px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 1132367421&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbjiozzolino@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMatias Rizzi\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/matias-rizzi\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/MATIAS-RIZZI-e1753405922279.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb120px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 34755928&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbrizzim@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSoledad Natalia Dominguez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/soledad-natalia-dominguez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/07\/WhatsApp-Image-2024-07-03-at-2.38.22-PM.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb98px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-40px||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 55735956&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbsdominguez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGaston Barrera\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/gaston-barrera\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/07\/Diseno-sin-titulo-1-1.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb112px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb90.5px\u00bb custom_margin=\u00bb20px||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 68828884&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbbgaston@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGabriel Ziccardi\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/gabriel-ziccardi\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/08\/GABRIEL-ZICCARDI-1.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb102px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 63549999&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbgziccardi@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbPablo Manlio\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/pablo-manlio\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/09\/PABLO-MANLIO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb102px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb93.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 66933033&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb28px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbpmanlio@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDaniel Wilhelm\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/daniel-wilhelm\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/09\/DANIEL-WILHELM.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb102px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 32824993&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbgziccardi@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbPatricia Cebenko\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/patricia-cebenko\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/09\/PATRICIA-CEBENKO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb136px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 49358292&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbpcebenko@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bb\u00c1ngeles Palavecino\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/angeles-palavecino\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2024\/09\/ANGELES-PALAVECINO-OFICIAL-.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb136px\u00bb content_max_width=\u00bb505px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb124.3px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 55962909&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbapalavecino@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbLara Vieytes\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/lara-vieytes\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/01\/LARA-VIEYTES-FOTO-RECORTADA.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb100px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 25115863&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bblaravieytes@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMelina Maccario\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/mariela-towstyj\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/01\/MELINA-MACCARIO.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb88px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 37962667&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmelinamaccario@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbElias Vico\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/elias-vico\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-29-at-17.02.30-1.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb120px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 38315053&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbeliasvico@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbEsthefanie Vasquez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/esthefanie-vasquez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/01\/WhatsApp-Image-2025-01-29-at-18.08.32.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb5px||||false|false\u00bb min_height=\u00bb100px\u00bb custom_margin=\u00bb|||-20px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 51344989&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-20px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbesthefanievasquez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-20px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAnalia Flego\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/analia-flego\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/03\/FOTO-ANALIA-ALMA-FLEGO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb81px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 36800574&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbanaliaflego@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbPablo Petrola\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/pablo-petrola\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/02\/PABLO-PETROLA-FOTO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb92px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 64843217&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbpablopetrola@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSilvina Tortora\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/silvina-tortora\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/03\/WhatsApp-Image-2025-03-27-at-15.15.20.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb91px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 59519481&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbsilvinatortora@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbNatalia Primo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/natalia-primo\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/04\/NATALIA-PRIMO-FOTO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb92px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 32519436&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbnataliaprimo@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbElizabeth Luque\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/elizabeth-luque\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/05\/ELIZABETH-LUQUE-FOTO-.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 57215759&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbrodriguezjulian@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAna Acu\u00f1a\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/ana-acuna\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/05\/ANA-ACUNA.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb89px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 51253809&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbanaacuna@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFernanda Panossian\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/fernanda-panossian\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/05\/FERNANDA-PANOSSIAN-FOTO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-15px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 67058174&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-15px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfernandapanossian@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb custom_margin=\u00bb|||-15px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFabian Mattarana\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/fabian-mattarana\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/07\/FABIAN-MATTARANA.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||||false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 67596314&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfabianmattarana@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFrancisco Claret\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/francisco-claret\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/09\/FRANCISCO-CLARET.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 63219307&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfranciscoclaret@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMateo Gomez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/mateo-gomez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/08\/MATEO-GOMEZ-FOTO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 26359287&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmateogomez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbSheila Lopez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/sheila-lopez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/10\/SHEILA-BELEN-LOPEZ-FOTO.jpg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 64168037&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbsheilalopez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbIgnacio Esparrach\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/caterina-cigola\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2025\/08\/Ignacio-esparrach.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb15 56911678&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbignacioesparrach@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDaniel Barrionuevo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/daniel-barrionuevo\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/01\/Diseno-sin-titulo-93.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 30619433&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbjuliobarrionuevo@remax.com.ar \u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGabriela Fernandez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/gabriela-fernandez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/02\/GABRIELA-FERNANDEZ-FOTO.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb105px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 67262100&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfgabriela@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFederico Alfonso\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/federico-alfonso\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/02\/FEDERICO-ALFONSO-FOTO.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb110px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-40px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 44072309&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfalfonso@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbLuciano Iovanna\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/luciano-iovanna\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/03\/LUCIANO-IOVANNA-FOTO-1.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb10px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 31147700&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bblucianoiovanna@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMiguel Halife\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/miguel-halife\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/02\/MIGUEL.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb100px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-10px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 91886919&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmhalife@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbRonan Miller\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/ronan-miller\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bb#FFFFFF\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/c50ef3bc-b1a5-48fc-a02e-b69b95c4b362.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb85px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-20px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 31534444&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbrmiller@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbAlejandro Bobillo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/alejandro-bobillo\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/02\/ALEJANDRO-BOBILLO.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb120px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-55px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 58400107&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbabobillo@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbCandela Carrizo\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/candela-carrizo\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/Candela-Carrizo.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 68592898&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbcandelacarrizo@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFacundo Gomez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/facundo-gomez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/05\/Facundo-Gomez.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-30px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||25px|-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 61958586&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbfacundogomez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbEvangelina Mazzei\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/evangelina-mazzei\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/05\/Evangelina-Mazzei-2.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb120px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 63616147&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbevangelinamazzei@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbEmiliano Rodriguez\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/emiliano-rodriguez\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/WhatsApp-Image-2026-04-07-at-10.51.07-AM.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-50px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb||25px|-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 78917040&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbemilianorodriguez@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbGimena Valle\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/gimena-valle\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/04\/Gimena-Valle.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb115px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb92.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 38901313&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbgimenavalle@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbHernan Calles\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/hernan-calles\u00bb url_new_window=\u00bbon\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/06\/Hernan-Calles-1-e1781285965375.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb120px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb125.5px\u00bb custom_margin=\u00bb||15px|-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 25992236&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbhernancalles@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbCarolina Landi\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/carolina-landi\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bb#FFFFFF\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/06\/Gemini_Generated_Image_r5ggb9r5ggb9r5gg-e1781286709808.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb115.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 56404395&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bblandic@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbMartin Assad\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/martin-assad\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bb#FFFFFF\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/07\/Martin-Assad.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb115.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 49361460&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbmartinassad@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.16.1&#8243; background_color=\u00bb#ffffff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb60px|||\u00bb custom_padding=\u00bb60px|0px|60px|0px|false|false\u00bb animation_style=\u00bbslide\u00bb animation_direction=\u00bbbottom\u00bb animation_intensity_slide=\u00bb6%\u00bb animation_starting_opacity=\u00bb100%\u00bb border_radii=\u00bbon|15px|15px|15px|15px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_vertical=\u00bb39px\u00bb box_shadow_blur=\u00bb80px\u00bb box_shadow_color=\u00bbrgba(0,0,0,0.1)\u00bb custom_width_px=\u00bb1280px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbDiego Piccoli\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/diego-piccoli\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/07\/Diego-Piccoli.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb115.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 64276917&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbdiegopiccoli@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bb Matias Ferraro\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/matias-ferraro\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/07\/Matias-Ferraro.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb115.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 55023914&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb hover_enabled=\u00bb0&#8243; icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbmatiasferraro@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb30px|40px|30px|40px\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_blurb title=\u00bbFlorencia Fontana\u00bb url=\u00bbhttps:\/\/www.remax.com.ar\/agent\/florencia-fontana\u00bb url_new_window=\u00bbon\u00bb image_icon_background_color=\u00bbRGBA(255,255,255,0)\u00bb image=\u00bbhttps:\/\/remax-rio.com.ar\/wp-content\/uploads\/2026\/08\/Florencia-Fontana.png\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb125px\u00bb image_icon_width_tablet=\u00bb100px\u00bb image_icon_width_phone=\u00bb100px\u00bb image_icon_width_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_line_height=\u00bb1.4em\u00bb body_font=\u00bbLato|500|||||||\u00bb body_font_size=\u00bb16px\u00bb image_icon_custom_margin=\u00bb-25px||||false|false\u00bb min_height=\u00bb115.5px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb hover_enabled=\u00bb0&#8243; border_radii_image=\u00bbon|100px|100px|100px|100px\u00bb image_max_width=\u00bb100px\u00bb image_max_width_tablet=\u00bb\u00bb image_max_width_phone=\u00bb\u00bb image_max_width_last_edited=\u00bbon|desktop\u00bb global_colors_info=\u00bb{}\u00bb title_text=\u00bbFlorencia Fontana\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>Agente<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=\u00bb+54 9 11 23223299&#8243; use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe090;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb min_height=\u00bb27px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb hover_enabled=\u00bb0&#8243; icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][et_pb_blurb title=\u00bbflorenciafontana@remax.com.ar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe076;||divi||400&#8243; icon_color=\u00bb#3c39e6&#8243; icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb18px\u00bb _builder_version=\u00bb4.16.1&#8243; header_font=\u00bbLato|700|||||||\u00bb header_font_size=\u00bb15px\u00bb header_letter_spacing=\u00bb1px\u00bb custom_margin=\u00bb|||-10px|false|false\u00bb hover_enabled=\u00bb0&#8243; icon_font_size=\u00bb18px\u00bb global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros Agentes Te presentamos los mejores agentes inmobiliarios que en equipo, junto con la martillera te ayudar\u00e1n a cumplir tus sue\u00f1os, porque en RE \/ MAX RIO lo m\u00e1s importante sos vos.AgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgenteAgente<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-61","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/61","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=61"}],"version-history":[{"count":194,"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions"}],"predecessor-version":[{"id":22382,"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/pages\/61\/revisions\/22382"}],"wp:attachment":[{"href":"https:\/\/remax-rio.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}